{"id":226,"date":"2025-09-06T11:46:54","date_gmt":"2025-09-06T11:46:54","guid":{"rendered":"https:\/\/stpaulscbe.edu.in\/equity\/?page_id=226"},"modified":"2025-09-06T11:52:43","modified_gmt":"2025-09-06T11:52:43","slug":"testimonial","status":"publish","type":"page","link":"https:\/\/stpaulscbe.edu.in\/equity\/testimonial\/","title":{"rendered":"Testimonial"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"226\" class=\"elementor elementor-226\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a032d41 e-flex e-con-boxed e-con e-parent\" data-id=\"a032d41\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb277e4 elementor-widget elementor-widget-heading\" data-id=\"bb277e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Testimonial<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-824627d e-flex e-con-boxed e-con e-parent\" data-id=\"824627d\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9e7d504 e-con-full e-flex e-con e-child\" data-id=\"9e7d504\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e23915 e-con-full e-flex e-con e-child\" data-id=\"2e23915\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f96dce elementor-widget elementor-widget-image\" data-id=\"2f96dce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1152\" height=\"864\" src=\"https:\/\/stpaulscbe.edu.in\/equity\/wp-content\/uploads\/2025\/09\/scl.jpg\" class=\"attachment-full size-full wp-image-241\" alt=\"\" srcset=\"https:\/\/stpaulscbe.edu.in\/equity\/wp-content\/uploads\/2025\/09\/scl.jpg 1152w, https:\/\/stpaulscbe.edu.in\/equity\/wp-content\/uploads\/2025\/09\/scl-300x225.jpg 300w, https:\/\/stpaulscbe.edu.in\/equity\/wp-content\/uploads\/2025\/09\/scl-1024x768.jpg 1024w, https:\/\/stpaulscbe.edu.in\/equity\/wp-content\/uploads\/2025\/09\/scl-768x576.jpg 768w\" sizes=\"(max-width: 1152px) 100vw, 1152px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af5351f e-con-full e-flex e-con e-child\" data-id=\"af5351f\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Testimonial<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/pages\/226"}],"collection":[{"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/comments?post=226"}],"version-history":[{"count":13,"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/pages\/226\/revisions"}],"predecessor-version":[{"id":250,"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/pages\/226\/revisions\/250"}],"wp:attachment":[{"href":"https:\/\/stpaulscbe.edu.in\/equity\/wp-json\/wp\/v2\/media?parent=226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}